{"id":12512,"date":"2021-03-10T11:51:37","date_gmt":"2021-03-10T11:51:37","guid":{"rendered":"https:\/\/pasitoapasito1.wpengine.com\/politica-de-cookies\/"},"modified":"2021-05-14T07:31:39","modified_gmt":"2021-05-14T07:31:39","slug":"informativa-sui-cookie","status":"publish","type":"page","link":"https:\/\/pasitoapasito.es\/it\/informativa-sui-cookie\/","title":{"rendered":"Informativa sui cookie"},"content":{"rendered":"\n<div class=\"wp-block-hacce-wrapper legaleswraper\">\n<p><strong><strong>Ultimo aggiornamento:<\/strong><\/strong> 30 Abril 2021<\/p>\n\n\n\n<p><strong><strong>DISET, S.A.<\/strong> <\/strong>(di seguito, <strong>\u201c<strong>DISET\u201d<\/strong>)<\/strong>, tramite la presente Informativa sui Cookie adempie all&#8217;impegno acquisito ai sensi della normativa vigente sull&#8217;uso dei cookie, fornendo agli utenti le informazioni che consentono loro di capire quali tipi di cookie vengono utilizzati e a quale scopo, al fine di fornire trasparenza in merito ai dati trattati con la navigazione sul nostro sito Web  <a data-type=\"URL\" data-id=\"pasitoapasito.es\" href=\"https:\/\/pasitoapasito1.wpengine.com\">pasitoapasito.es<\/a>&nbsp;(di seguito, il \u201c<strong>sito Web<\/strong>\u201d).<\/p>\n\n\n\n<p>La presente informativa \u00e8 revisionata periodicamente al fine di garantirne la validit\u00e0, potendo quindi essere modificata. Ti consigliamo di visitare regolarmente il sito Web sul quale vi informeremo degli eventuali aggiornamenti al riguardo.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong><strong>1. Cosa sono i cookie?<\/strong><\/strong><\/h4>\n\n\n\n<p>I cookie sono stringhe di testo di piccole dimensioni inviate dal sito Web visitato al proprio terminale, che vengono utilizzate per registrare determinate interazioni di navigazione con tale sito, con la conseguente memorizzazione dei dati eventualmente aggiornabili e recuperabili. Tali stringhe sono memorizzate sul computer dell&#8217;Utente e contengono dati anonimi non dannosi al computer. Sono utilizzate principalmente per ricordare le preferenze dell&#8217;Utente, quali la lingua selezionata, i dati di accesso o la personalizzazione del sito Web.<\/p>\n\n\n\n<p>I cookie possono essere utilizzati anche per registrare informazioni anonime su come un visitatore utilizza un determinato sito. Ad esempio, da quale sito web ha effettuato l&#8217;accesso, se ha utilizzato un Banner pubblicitario per arrivarci o per ricordare le proprie preferenze di navigazione.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>2. Perch\u00e9 utilizziamo i cookie?<\/strong><\/h4>\n\n\n\n<p>La <strong>DISET<\/strong> usa i cookie strettamente necessari ed essenziali all&#8217;uso del nostro sito Web da parte dell&#8217;Utente, consentendogli di muoversi liberamente, di utilizzare le nostre aree protette, di personalizzare le diverse opzioni, ecc.&nbsp;<\/p>\n\n\n\n<p>La <strong>DISET<\/strong> utilizza altres\u00ec i cookie che raccolgono i dati relativi all&#8217;analisi dell&#8217;uso del sito Web. Sono utilizzati per migliorare il servizio all&#8217;utente, misurando l&#8217;utilizzo e le prestazioni del sito Web, allo scopo di ottimizzarlo e di personalizzarlo.<\/p>\n\n\n\n<p>Sul presente sito Web sono utilizzati o possono essere utilizzati collegamenti ipertestuali che consentono un collegamento o link ad altri siti Web. La <strong>DISET<\/strong> non controlla i cookie usati dai suddetti siti web esterni. Per ulteriori informazioni sui cookie di tali siti Web terzi, consigliamo di vedere le loro informative sui cookie.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong><strong>3. Quale uso facciamo dei diversi tipi di cookie?<\/strong><\/strong><\/h4>\n\n\n\n<p><strong>Cookie tecnici:<\/strong> Sono i cookie essenziali e strettamente necessari al corretto funzionamento del sito Web e all&#8217;uso delle diverse opzioni e servizi offerti su di esso. Ad esempio, sono quelli utilizzati per il monitoraggio della sessione, la gestione del tempo di risposta, l&#8217;esecuzione o la convalida delle opzioni, l&#8217;uso di elementi di sicurezza, per condividere contenuti sui social network, ecc.<\/p>\n\n\n\n<p><strong>Cookie analitici:<\/strong> Sono quelli utilizzati per creare i profili di navigazione e per conoscere le preferenze dell&#8217;utente allo scopo di migliorare l&#8217;offerta di prodotti e servizi.<\/p>\n\n\n\n<p><strong>Cookie pubblicitari:<\/strong> Sono quelli che consentono di gestire l&#8217;offerta degli spazi pubblicitari presenti sul sito Web, adattando il contenuto della pubblicit\u00e0 al contenuto del servizio richiesto, all&#8217;uso del sito Web o alle informazioni disponibili sulle abitudini di navigazione su Internet.<\/p>\n\n\n\n<p>Sono riportati schematicamente di seguito i cookie utilizzati sul sito Web:<\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table><tbody><tr><td><strong>Nombre de la cookie<\/strong><\/td><td><strong>Duraci\u00f3n<\/strong><\/td><td><strong>Uso<\/strong><\/td><\/tr><tr><td><br>_gat<\/td><td><br>1 minuto.<\/td><td><br>Se usan para limitar el porcentaje de solicitudesSe usan para limitar el porcentaje de solicitudes<\/td><\/tr><tr><td>_gid.<br><\/td><td>2 A\u00f1os.<br><\/td><td>Se usa para distinguir a los usuarios.<br><\/td><\/tr><tr><td><br>_ga.<\/td><td><br>24 horas.<\/td><td><br>Se usa para distinguir a los usuarios.<\/td><\/tr><tr><td><br><\/td><td><br><\/td><td><br><\/td><\/tr><tr><td><br><\/td><td><br><\/td><td><br><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\"><strong><strong>4. Cosa succede se accetto l&#8217;Informativa sui Cookie?<\/strong><\/strong><\/h4>\n\n\n\n<p>L&#8217;accettazione della nostra Informativa sui cookie ci consente di migliorare il sito Web, offrendovi un accesso ottimale e un servizio pi\u00f9 efficiente e personalizzato.<\/p>\n\n\n\n<p>Potete comunque modificare il vostro consenso e selezionare le vostre preferenze sulla tabella delle impostazioni dei cookie accessibile dal banner per l&#8217;uso dei cookie alla home e\/o modificando le impostazioni dei cookie a seconda del browser utilizzato, seguendo le indicazioni di questo paragrafo.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong><strong>5. Come posso disabilitare i cookie?<\/strong><\/strong><\/h4>\n\n\n\n<p>In ottemperanza della normativa in vigore, bisogna chiedere il vostro permesso per gestire i cookie. Dalla tabella delle impostazioni dei cookie \u00e8 possibile autorizzare o meno i cookie a seconda della loro tipologia. Se decidete di non autorizzare il trattamento indicando la non conformit\u00e0, utilizzeremo esclusivamente i cookie tecnici per essere essenziali alla navigazione sul nostro sito Web. In tale caso, non memorizzeremo altri cookie.&nbsp;<\/p>\n\n\n\n<p>Vi informiamo che, oltre alla tabella delle impostazioni dei cookie, che vi consente di modificare, eliminare e\/o impedire l&#8217;uso dei cookie, \u00e8 anche possibile svolgere tali azioni impostando i cookie sul vostro browser:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"http:\/\/support.google.com\/chrome\/answer\/95647?hl=es\">Impostazioni dei cookie su Google Chrome.<\/a><\/li><li><a href=\"http:\/\/www.apple.com\/es\/privacy\/use-of-cookies\/\">Impostazioni dei cookie su Safari.<\/a><\/li><li><a href=\"about:blank\">Impostazioni dei cookie su Firefox.<\/a><\/li><li><a href=\"about:blank\">Impostazioni dei cookie su Internet Explorer.<\/a><\/li><\/ul>\n\n\n\n<p>Questi browser sono soggetti ad aggiornamenti o modifiche, non potendo quindi noi garantire la loro piena compatibilit\u00e0 con la versione del vostro browser. \u00c8 anche possibile che state utilizzando un browser diverso da quelli vincolati a tali link, quali Konqueror, Arora, Flock, ecc. Per evitare tali incompatibilit\u00e0, potete accedere direttamente dal vostro browser alle opzioni, che in genere sono alla sezione \u201cPrivacy\u201d del men\u00f9 \u201cOpzioni\u201d. Per ulteriori informazioni, consultare la sezione Aiuto del vostro browser.<\/p>\n\n\n\n<p><strong><strong>Ulteriori informazioni sulla tutela dei dati:<\/strong><\/strong><\/p>\n\n\n\n<p>I dati personali saranno conservati per un periodo di tempo non superiore a quello strettamente necessario al conseguimento delle finalit\u00e0 per le quali sono stati raccolti, e fintanto dura la causa che ha legittimato il trattamento di tali dati personali. Al termine della causa che ha legittimato il trattamento, i dati personali saranno conservati opportunamente bloccati per il periodo di tempo consentito dalle normative legali per evitare eventuali infrazioni.Potete esercitare i vostri diritti di accesso, rettifica, cancellazione, limitazione, portabilit\u00e0 o opposizione al trattamento dei propri dati in qualunque momento, compresa la possibilit\u00e0 di presentare un reclamo qualora ritenete che la <strong>DISET<\/strong> sta trattando i vostri dati personali in modo inappropriato, inoltrando una comunicazione per iscritto alla <strong>DISET<\/strong>, Calle C, n\u00ba 3, Sector B, Zona Franca, 08040 Barcellona, o una email a <a href=\"mailto:info@pasitoapasito.es\">info@pasitoapasito.es<\/a><\/p>\n\n\n\n<p>Potete utilizzare i modelli e i form relativi ai precedenti diritti disponibili sul sito ufficiale dell&#8217;Agenzia Spagnola per la Tutela dei Dati (<a href=\"https:\/\/www.aepd.es\/es\/derechos-y-deberes\/conoce-tus-derechos\">https:\/\/www.aepd.es\/es\/derechos-y-deberes\/conoce-tus-derechos<\/a>). Se ritenete che la <strong>DISET<\/strong> tratta i vostri dati personali in modo inappropriato, potete inoltrare i vostri reclami a tale Autorit\u00e0 di Controllo.<\/p>\n\n\n\n<p>Per ulteriori informazioni sul trattamento dei vostri dati personali, vi preghiamo di consultare la nostra <a href=\"https:\/\/pasitoapasito1.wpengine.com\/informativa-sulla-privacy\/?lang=it\">Informativa sulla Privacy<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-12512","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Informativa sui cookie - Pasito a Pasito<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pasitoapasito.es\/it\/informativa-sui-cookie\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Informativa sui cookie - Pasito a Pasito\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pasitoapasito.es\/it\/informativa-sui-cookie\/\" \/>\n<meta property=\"og:site_name\" content=\"Pasito a Pasito\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-14T07:31:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pasitoapasito.es\\\/it\\\/informativa-sui-cookie\\\/\",\"url\":\"https:\\\/\\\/pasitoapasito.es\\\/it\\\/informativa-sui-cookie\\\/\",\"name\":\"Informativa sui cookie - Pasito a Pasito\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pasitoapasito.es\\\/fr\\\/#website\"},\"datePublished\":\"2021-03-10T11:51:37+00:00\",\"dateModified\":\"2021-05-14T07:31:39+00:00\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pasitoapasito.es\\\/it\\\/informativa-sui-cookie\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pasitoapasito.es\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/pasitoapasito.es\\\/fr\\\/\",\"name\":\"Pasito a Pasito\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pasitoapasito.es\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Informativa sui cookie - Pasito a Pasito","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pasitoapasito.es\/it\/informativa-sui-cookie\/","og_locale":"it_IT","og_type":"article","og_title":"Informativa sui cookie - Pasito a Pasito","og_url":"https:\/\/pasitoapasito.es\/it\/informativa-sui-cookie\/","og_site_name":"Pasito a Pasito","article_modified_time":"2021-05-14T07:31:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pasitoapasito.es\/it\/informativa-sui-cookie\/","url":"https:\/\/pasitoapasito.es\/it\/informativa-sui-cookie\/","name":"Informativa sui cookie - Pasito a Pasito","isPartOf":{"@id":"https:\/\/pasitoapasito.es\/fr\/#website"},"datePublished":"2021-03-10T11:51:37+00:00","dateModified":"2021-05-14T07:31:39+00:00","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pasitoapasito.es\/it\/informativa-sui-cookie\/"]}]},{"@type":"WebSite","@id":"https:\/\/pasitoapasito.es\/fr\/#website","url":"https:\/\/pasitoapasito.es\/fr\/","name":"Pasito a Pasito","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pasitoapasito.es\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/pasitoapasito.es\/it\/wp-json\/wp\/v2\/pages\/12512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pasitoapasito.es\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/pasitoapasito.es\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/pasitoapasito.es\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pasitoapasito.es\/it\/wp-json\/wp\/v2\/comments?post=12512"}],"version-history":[{"count":0,"href":"https:\/\/pasitoapasito.es\/it\/wp-json\/wp\/v2\/pages\/12512\/revisions"}],"wp:attachment":[{"href":"https:\/\/pasitoapasito.es\/it\/wp-json\/wp\/v2\/media?parent=12512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}